{"id":119,"count":94,"description":"","link":"https:\/\/www.hrishikeshyoga.com\/blog\/category\/yoga\/","name":"Yoga","slug":"yoga","taxonomy":"category","parent":0,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.hrishikeshyoga.com\/blog\/category\/yoga\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hrishikeshyoga.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/119\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hrishikeshyoga.com\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hrishikeshyoga.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hrishikeshyoga.com\\\/blog\\\/category\\\/yoga\\\/#listItem\",\"name\":\"Yoga\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hrishikeshyoga.com\\\/blog\\\/category\\\/yoga\\\/#listItem\",\"position\":2,\"name\":\"Yoga\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hrishikeshyoga.com\\\/blog#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.hrishikeshyoga.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/119\\\/#collectionpage\",\"url\":\"https:\\\/\\\/www.hrishikeshyoga.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/119\\\/\",\"name\":\"Yoga -\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hrishikeshyoga.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hrishikeshyoga.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/119\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hrishikeshyoga.com\\\/blog\\\/#organization\",\"name\":\"Hrishikesh Yoga\",\"description\":\"Best Yoga School in Rishikesh\",\"url\":\"https:\\\/\\\/www.hrishikeshyoga.com\\\/blog\\\/\",\"telephone\":\"+918126988546\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.hrishikeshyoga.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/new-hrs-logo.png?fit=150%2C150&ssl=1\",\"@id\":\"https:\\\/\\\/www.hrishikeshyoga.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/119\\\/#organizationLogo\",\"width\":150,\"height\":150},\"image\":{\"@id\":\"https:\\\/\\\/www.hrishikeshyoga.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/119\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hrishikeshyoga.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.hrishikeshyoga.com\\\/blog\\\/\",\"name\":\"Hrishikesh Yoga\",\"description\":\"Best Yoga School in Rishikesh\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hrishikeshyoga.com\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Yoga -","description":"","canonical_url":"https:\/\/www.hrishikeshyoga.com\/blog\/category\/yoga\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.hrishikeshyoga.com\/blog\/wp-json\/wp\/v2\/categories\/119\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.hrishikeshyoga.com\/blog#listItem","position":1,"name":"Home","item":"https:\/\/www.hrishikeshyoga.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.hrishikeshyoga.com\/blog\/category\/yoga\/#listItem","name":"Yoga"}},{"@type":"ListItem","@id":"https:\/\/www.hrishikeshyoga.com\/blog\/category\/yoga\/#listItem","position":2,"name":"Yoga","previousItem":{"@type":"ListItem","@id":"https:\/\/www.hrishikeshyoga.com\/blog#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/www.hrishikeshyoga.com\/blog\/wp-json\/wp\/v2\/categories\/119\/#collectionpage","url":"https:\/\/www.hrishikeshyoga.com\/blog\/wp-json\/wp\/v2\/categories\/119\/","name":"Yoga -","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.hrishikeshyoga.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.hrishikeshyoga.com\/blog\/wp-json\/wp\/v2\/categories\/119\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/www.hrishikeshyoga.com\/blog\/#organization","name":"Hrishikesh Yoga","description":"Best Yoga School in Rishikesh","url":"https:\/\/www.hrishikeshyoga.com\/blog\/","telephone":"+918126988546","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.hrishikeshyoga.com\/blog\/wp-content\/uploads\/2024\/08\/new-hrs-logo.png?fit=150%2C150&ssl=1","@id":"https:\/\/www.hrishikeshyoga.com\/blog\/wp-json\/wp\/v2\/categories\/119\/#organizationLogo","width":150,"height":150},"image":{"@id":"https:\/\/www.hrishikeshyoga.com\/blog\/wp-json\/wp\/v2\/categories\/119\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/www.hrishikeshyoga.com\/blog\/#website","url":"https:\/\/www.hrishikeshyoga.com\/blog\/","name":"Hrishikesh Yoga","description":"Best Yoga School in Rishikesh","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.hrishikeshyoga.com\/blog\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.hrishikeshyoga.com\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tYoga\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.hrishikeshyoga.com\/blog"},{"label":"Yoga","link":"https:\/\/www.hrishikeshyoga.com\/blog\/category\/yoga\/"}],"_links":{"self":[{"href":"https:\/\/www.hrishikeshyoga.com\/blog\/wp-json\/wp\/v2\/categories\/119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hrishikeshyoga.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.hrishikeshyoga.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.hrishikeshyoga.com\/blog\/wp-json\/wp\/v2\/posts?categories=119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}